{"id":1387,"date":"2021-07-27T01:28:06","date_gmt":"2021-07-26T23:28:06","guid":{"rendered":"https:\/\/rhosonics.com\/?p=1387"},"modified":"2025-05-20T14:55:56","modified_gmt":"2025-05-20T12:55:56","slug":"donations-to-red-cross","status":"publish","type":"post","link":"https:\/\/rhosonics.com\/fr\/insight\/nouvelles\/dons-a-la-croix-rouge\/","title":{"rendered":"Dons \u00e0 la Croix-Rouge"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>Depuis le d\u00e9but de l'ann\u00e9e derni\u00e8re, nous avons demand\u00e9 aux professionnels de l'industrie de participer \u00e0 notre \u00e9tude de march\u00e9 sur la mesure de la densit\u00e9. L'objectif de cette enqu\u00eate est de mieux comprendre la demande des clients. Plus de 65 r\u00e9pondants ont fait part de leurs motivations et de leurs pr\u00e9f\u00e9rences en mati\u00e8re de mesure de la densit\u00e9. Pour evparticipantipan,t nous avons fait don de $5 \u00e0 la <a href=\"https:\/\/www.icrc.org\/en\/donate\/covid-19-emergency-appeal\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Int. Appel du Comit\u00e9 de la Croix-Rouge Covid-19<\/span><\/a>.<\/p>\n<p>En outre, nous avons interrog\u00e9 des experts de l'industrie du traitement des min\u00e9raux sur des sujets sp\u00e9cifiques li\u00e9s aux instruments de mesure de la densit\u00e9. Ces informations sont utilis\u00e9es \u00e0 des fins de d\u00e9veloppement de produits. Pour chaque entretien, nous avons fait don de $50 \u00e0 la Croix-Rouge.<\/p>\n<p>Les \u00e9quipes du Comit\u00e9 international de la Croix-Rouge (CICR) luttent pour emp\u00eacher la propagation du virus Covid-19. Croix-Rouge luttent pour emp\u00eacher la propagation du virus Covid-19 en soutenant les centres de soins vitaux et en fournissant des articles essentiels tels que du savon et des masques. Au nom de nos participants, nous avons fait don d'un total de $545 au Comit\u00e9 de la Croix-Rouge.<\/p>\n<p>Nous tenons \u00e0 remercier tous ceux qui ont particip\u00e9 \u00e0 notre enqu\u00eate. Vos r\u00e9ponses sont tr\u00e8s appr\u00e9ci\u00e9es et nous aideront \u00e0 mieux r\u00e9pondre \u00e0 la demande du march\u00e9. <\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:5%;width:100%;\"><div class=\"fusion-separator-border sep-double\" style=\"--awb-height:20px;--awb-amount:20px;border-color:var(--awb-color3);border-top-width:1px;border-bottom-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-2\"><p>Vous souhaitez recevoir des mises \u00e0 jour fr\u00e9quentes sur nos produits ? Alors n'h\u00e9sitez pas \u00e0 <a href=\"https:\/\/rhosonics.com\/fr\/contact\/\"><u>s'inscrire \u00e0 notre lettre d'information<\/u><\/a> ou suivez-nous sur <a href=\"https:\/\/www.linkedin.com\/company\/rhosonics-analytical-bv\" target=\"_blank\" rel=\"noopener\"><u>LinkedIn.<\/u><\/a><\/p>\n<\/div><\/div><\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>L'objectif de cette enqu\u00eate est de mieux comprendre la demande des clients. Plus de 65 r\u00e9pondants ont fait part de leurs motivations et de leurs pr\u00e9f\u00e9rences en mati\u00e8re de mesure de la densit\u00e9. Pour chaque participant, nous avons fait don de $5 \u00e0 l'appel du Comit\u00e9 Covid-19 de la Croix-Rouge internationale. Comit\u00e9 de la Croix-Rouge Covid-19.<\/p>","protected":false},"author":3,"featured_media":1844,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/rhosonics.com\/fr\/wp-json\/wp\/v2\/posts\/1387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rhosonics.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rhosonics.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rhosonics.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/rhosonics.com\/fr\/wp-json\/wp\/v2\/comments?post=1387"}],"version-history":[{"count":0,"href":"https:\/\/rhosonics.com\/fr\/wp-json\/wp\/v2\/posts\/1387\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rhosonics.com\/fr\/wp-json\/wp\/v2\/media\/1844"}],"wp:attachment":[{"href":"https:\/\/rhosonics.com\/fr\/wp-json\/wp\/v2\/media?parent=1387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rhosonics.com\/fr\/wp-json\/wp\/v2\/categories?post=1387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rhosonics.com\/fr\/wp-json\/wp\/v2\/tags?post=1387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}